{"id":3238,"date":"2016-10-08T09:14:18","date_gmt":"2016-10-08T09:14:18","guid":{"rendered":"http:\/\/www.fundaciosorigue.com\/wp-content\/uploads\/2016\/06\/O-Manual_Fundacio_Sorigue_CAST-1.pdf"},"modified":"2016-10-08T09:14:18","modified_gmt":"2016-10-08T09:14:18","slug":"o-manual_fundacio_sorigue_cast-3","status":"inherit","type":"attachment","link":"https:\/\/fundaciosorigue.com\/en\/press-room\/o-manual_fundacio_sorigue_cast-3\/","title":{"rendered":"o-manual_fundacio_sorigue_cast"},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-3238","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>o-manual_fundacio_sorigue_cast - Fundaci\u00f3 Sorigu\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.fundaciosorigue.com\/en\/wp-content\/uploads\/2016\/06\/O-Manual_Fundacio_Sorigue_CAST-1.pdf\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"o-manual_fundacio_sorigue_cast - Fundaci\u00f3 Sorigu\u00e9\" \/>\n<meta property=\"og:description\" content=\"o-manual_fundacio_sorigue_cast\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.fundaciosorigue.com\/wp-content\/uploads\/2016\/06\/O-Manual_Fundacio_Sorigue_CAST-1.pdf\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Sorigu\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.fundaciosorigue.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/O-Manual_Fundacio_Sorigue_CAST-1.pdf\",\"url\":\"http:\\\/\\\/www.fundaciosorigue.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/O-Manual_Fundacio_Sorigue_CAST-1.pdf\",\"name\":\"o-manual_fundacio_sorigue_cast - Fundaci\u00f3 Sorigu\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fundaciosorigue.com\\\/#website\"},\"datePublished\":\"2016-10-08T09:14:18+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.fundaciosorigue.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/O-Manual_Fundacio_Sorigue_CAST-1.pdf#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.fundaciosorigue.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/O-Manual_Fundacio_Sorigue_CAST-1.pdf\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.fundaciosorigue.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/O-Manual_Fundacio_Sorigue_CAST-1.pdf#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fundaciosorigue.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Press room\",\"item\":\"http:\\\/\\\/www.fundaciosorigue.com\\\/en\\\/press-room\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"o-manual_fundacio_sorigue_cast\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fundaciosorigue.com\\\/#website\",\"url\":\"https:\\\/\\\/www.fundaciosorigue.com\\\/\",\"name\":\"Fundaci\u00f3 Sorigu\u00e9\",\"description\":\"Fundaci\u00f3 d&#039;art contemporani de Lleida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fundaciosorigue.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"o-manual_fundacio_sorigue_cast - Fundaci\u00f3 Sorigu\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.fundaciosorigue.com\/en\/wp-content\/uploads\/2016\/06\/O-Manual_Fundacio_Sorigue_CAST-1.pdf","og_locale":"en_US","og_type":"article","og_title":"o-manual_fundacio_sorigue_cast - Fundaci\u00f3 Sorigu\u00e9","og_description":"o-manual_fundacio_sorigue_cast","og_url":"http:\/\/www.fundaciosorigue.com\/wp-content\/uploads\/2016\/06\/O-Manual_Fundacio_Sorigue_CAST-1.pdf","og_site_name":"Fundaci\u00f3 Sorigu\u00e9","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.fundaciosorigue.com\/wp-content\/uploads\/2016\/06\/O-Manual_Fundacio_Sorigue_CAST-1.pdf","url":"http:\/\/www.fundaciosorigue.com\/wp-content\/uploads\/2016\/06\/O-Manual_Fundacio_Sorigue_CAST-1.pdf","name":"o-manual_fundacio_sorigue_cast - Fundaci\u00f3 Sorigu\u00e9","isPartOf":{"@id":"https:\/\/www.fundaciosorigue.com\/#website"},"datePublished":"2016-10-08T09:14:18+00:00","breadcrumb":{"@id":"http:\/\/www.fundaciosorigue.com\/wp-content\/uploads\/2016\/06\/O-Manual_Fundacio_Sorigue_CAST-1.pdf#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.fundaciosorigue.com\/wp-content\/uploads\/2016\/06\/O-Manual_Fundacio_Sorigue_CAST-1.pdf"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.fundaciosorigue.com\/wp-content\/uploads\/2016\/06\/O-Manual_Fundacio_Sorigue_CAST-1.pdf#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fundaciosorigue.com\/en\/"},{"@type":"ListItem","position":2,"name":"Press room","item":"http:\/\/www.fundaciosorigue.com\/en\/press-room\/"},{"@type":"ListItem","position":3,"name":"o-manual_fundacio_sorigue_cast"}]},{"@type":"WebSite","@id":"https:\/\/www.fundaciosorigue.com\/#website","url":"https:\/\/www.fundaciosorigue.com\/","name":"Fundaci\u00f3 Sorigu\u00e9","description":"Fundaci\u00f3 d&#039;art contemporani de Lleida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fundaciosorigue.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/fundaciosorigue.com\/wp-content\/uploads\/2016\/06\/O-Manual_Fundacio_Sorigue_CAST-1.pdf'>o-manual_fundacio_sorigue_cast<\/a><\/p>\n"},"caption":{"rendered":"<p>o-manual_fundacio_sorigue_cast<\/p>\n"},"alt_text":"","media_type":"file","mime_type":"application\/pdf","media_details":{},"post":2898,"source_url":"https:\/\/fundaciosorigue.com\/wp-content\/uploads\/2016\/06\/O-Manual_Fundacio_Sorigue_CAST-1.pdf","filename":"O-Manual_Fundacio_Sorigue_CAST-1.pdf","filesize":1847180,"_links":{"self":[{"href":"https:\/\/fundaciosorigue.com\/en\/wp-json\/wp\/v2\/media\/3238\/"}],"collection":[{"href":"https:\/\/fundaciosorigue.com\/en\/wp-json\/wp\/v2\/media\/"}],"about":[{"href":"https:\/\/fundaciosorigue.com\/en\/wp-json\/wp\/v2\/types\/attachment\/"}],"author":[{"embeddable":true,"href":"https:\/\/fundaciosorigue.com\/en\/wp-json\/wp\/v2\/users\/5\/"}],"replies":[{"embeddable":true,"href":"https:\/\/fundaciosorigue.com\/en\/wp-json\/wp\/v2\/comments\/?post=3238"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":2898,"href":"https:\/\/fundaciosorigue.com\/en\/wp-json\/wp\/v2\/pages\/2898\/"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}